{"id":281,"date":"2020-01-23T16:25:23","date_gmt":"2020-01-23T19:25:23","guid":{"rendered":"https:\/\/ciram.epagri.sc.gov.br\/?page_id=281"},"modified":"2020-05-13T17:22:22","modified_gmt":"2020-05-13T20:22:22","slug":"notas-maritimas","status":"publish","type":"page","link":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/publicacoes\/notas-maritimas\/","title":{"rendered":"NOTAS MAR\u00cdTIMAS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"281\" class=\"elementor elementor-281\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65fdb364 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"65fdb364\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-578c2074\" data-id=\"578c2074\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-461f7f1d elementor-widget elementor-widget-shortcode\" data-id=\"461f7f1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"138\" class=\"elementor elementor-138\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17545da5 elementor-section-stretched elementor-hidden-mobile elementor-section-content-bottom elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"17545da5\" data-element_type=\"section\" data-e-type=\"section\" id=\"stickmenu\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7c8b0c05\" data-id=\"7c8b0c05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e9a0d2e elementor-widget elementor-widget-image\" data-id=\"7e9a0d2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.epagri.sc.gov.br\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"57\" height=\"62\" src=\"https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2020\/01\/Marca-Epagri-2026.png\" class=\"attachment-large size-large wp-image-47778\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1199f5b\" data-id=\"1199f5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f8b751 elementor-widget elementor-widget-image\" data-id=\"0f8b751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ciram.epagri.sc.gov.br\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"94\" height=\"60\" src=\"https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2020\/08\/LogoCiram.png\" class=\"attachment-large size-large wp-image-3037\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4f3b6ce6 elementor-sm-83\" data-id=\"4f3b6ce6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac16650 hfe-nav-menu__align-left hfe-submenu-icon-arrow hfe-submenu-animation-none hfe-link-redirect-child hfe-nav-menu__breakpoint-tablet elementor-widget elementor-widget-navigation-menu\" data-id=\"5ac16650\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:13,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;width_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:315,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:12,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;width_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-horizontal hfe-nav-menu-layout horizontal hfe-pointer__overline hfe-animation__slide\" data-layout=\"horizontal\">\n\t\t\t\t<div role=\"button\" class=\"hfe-nav-menu__toggle elementor-clickable\" tabindex=\"0\" aria-label=\"Menu Toggle\">\n\t\t\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\"  class=\"fas fa-align-justify\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-horizontal hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;fas fa-align-justify&quot;&gt;&lt;\/i&gt;\" data-close-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;far fa-window-close&quot;&gt;&lt;\/i&gt;\" data-full-width=\"yes\">\n\t\t\t\t\t<ul id=\"menu-1-5ac16650\" class=\"hfe-nav-menu\"><li id=\"menu-item-2815\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-ciram\/areas-de-atuacao\/\" class = \"hfe-menu-item\">O CIRAM<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-2729\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-ciram\/areas-de-atuacao\/\" class = \"hfe-sub-menu-item\">\u00c1reas de atua\u00e7\u00e3o<\/a><\/li>\n\t<li id=\"menu-item-333\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-ciram\/equipe\/\" class = \"hfe-sub-menu-item\">Equipe<\/a><\/li>\n\t<li id=\"menu-item-334\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-ciram\/quem-somos\/\" class = \"hfe-sub-menu-item\">Quem somos<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-3461\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/agricultura\/\" class = \"hfe-menu-item\">SOLU\u00c7\u00d5ES<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-3184\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/agricultura\/\" class = \"hfe-sub-menu-item\">Agricultura<\/a><\/li>\n\t<li id=\"menu-item-3185\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/tempo-e-clima\/\" class = \"hfe-sub-menu-item\">Tempo e Clima<\/a><\/li>\n\t<li id=\"menu-item-290\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/condicoes-extremas\/\" class = \"hfe-sub-menu-item\">Condi\u00e7\u00f5es extremas<span class='hfe-menu-toggle sub-arrow hfe-menu-child-1'><i class='fa'><\/i><\/span><\/a><\/div>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-1819\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/avisos-meteorologicos\/\" class = \"hfe-sub-menu-item\">Avisos Meteorol\u00f3gicos<\/a><\/li>\n\t\t<li id=\"menu-item-1818\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/avisos-hidrologicos\/\" class = \"hfe-sub-menu-item\">Avisos Hidrol\u00f3gicos<\/a><\/li>\n\t\t<li id=\"menu-item-2433\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/avisos-maritimos\/\" class = \"hfe-sub-menu-item\">Avisos Mar\u00edtimos<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-3183\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/rios\/\" class = \"hfe-sub-menu-item\">Rios<\/a><\/li>\n\t<li id=\"menu-item-3182\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/litoral\/\" class = \"hfe-sub-menu-item\">Litoral<\/a><\/li>\n\t<li id=\"menu-item-2474\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/monitoramento\/\" class = \"hfe-sub-menu-item\">Monitoramento<\/a><\/li>\n\t<li id=\"menu-item-2253\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/receba-nossos-boletins\/\" class = \"hfe-sub-menu-item\">Receba nossos boletins<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-2814\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/projetos\/projetos-concluidos\/\" class = \"hfe-menu-item\">PROJETOS<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-304\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/projetos\/projetos-concluidos\/\" class = \"hfe-sub-menu-item\">Projetos conclu\u00eddos<\/a><\/li>\n\t<li id=\"menu-item-305\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/projetos\/projetos-em-andamento\/\" class = \"hfe-sub-menu-item\">Projetos em andamento<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-2811\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/laudos-dados\/\" class = \"hfe-menu-item\">SERVI\u00c7OS<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-2237\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/laudos-dados\/\" class = \"hfe-sub-menu-item\">Laudos e dados ambientais<\/a><\/li>\n\t<li id=\"menu-item-2154\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-casan-peri\/\" class = \"hfe-sub-menu-item\">Casan<\/a><\/li>\n\t<li id=\"menu-item-11337\" class=\"menu-item menu-item-type-custom menu-item-object-custom hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/cad-fenomenos\/\" class = \"hfe-sub-menu-item\">Cadastro de fen\u00f4menos meteorol\u00f3gicos<\/a><\/li>\n\t<li id=\"menu-item-8540\" class=\"menu-item menu-item-type-custom menu-item-object-custom hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/dados-met\/\" class = \"hfe-sub-menu-item\">Mapas meteorol\u00f3gicos<\/a><\/li>\n\t<li id=\"menu-item-2155\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-queimados-projeto\/\" class = \"hfe-sub-menu-item\">Conc\u00f3rdia<\/a><\/li>\n\t<li id=\"menu-item-22546\" class=\"menu-item menu-item-type-custom menu-item-object-custom hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/solos\/\" class = \"hfe-sub-menu-item\">Sistema de solos<\/a><\/li>\n\t<li id=\"menu-item-24341\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-porto\/\" class = \"hfe-sub-menu-item\">Porto SFS<span class='hfe-menu-toggle sub-arrow hfe-menu-child-1'><i class='fa'><\/i><\/span><\/a><\/div>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-27800\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-porto\/\" class = \"hfe-sub-menu-item\">Monitoramento<\/a><\/li>\n\t\t<li id=\"menu-item-27798\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-porto-prev\/\" class = \"hfe-sub-menu-item\">Previs\u00e3o Tabelas<\/a><\/li>\n\t\t<li id=\"menu-item-27799\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-porto-prev-graf\/\" class = \"hfe-sub-menu-item\">Previs\u00e3o Gr\u00e1ficos<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li id=\"menu-item-39169\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/base-pra\/\" class = \"hfe-sub-menu-item\">Base-PRA<\/a><\/li>\n\t<li id=\"menu-item-42386\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/analisador-estiagens\/\" class = \"hfe-sub-menu-item\">Analisador de Estiagens<\/a><\/li>\n\t<li id=\"menu-item-48306\" class=\"menu-item menu-item-type-custom menu-item-object-custom hfe-creative-menu\"><a target=\"_blank\"rel=\"noopener\" href=\"https:\/\/ciram.epagri.sc.gov.br\/monitoramento_irani\/\" class = \"hfe-sub-menu-item\">Monitoramento &#8211; Irani S.A.<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-2813\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/publicacoes\/publicacoes-tecnico-cientificas\/\" class = \"hfe-menu-item\">PUBLICA\u00c7\u00d5ES<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-286\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/publicacoes\/publicacoes-tecnico-cientificas\/\" class = \"hfe-sub-menu-item\">Publica\u00e7\u00f5es t\u00e9cnico-cient\u00edficas<\/a><\/li>\n\t<li id=\"menu-item-27832\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\" tabindex=\"0\" role=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/livro-infantil-solos-floripa-2023\/\" class = \"hfe-sub-menu-item\">Publica\u00e7\u00f5es infantis<span class='hfe-menu-toggle sub-arrow hfe-menu-child-1'><i class='fa'><\/i><\/span><\/a><\/div>\n\t<ul class=\"sub-menu\">\n\t\t<li id=\"menu-item-43315\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-tesouro-do-meu-avo\/\" class = \"hfe-sub-menu-item\">O Tesouro do Meu Av\u00f4<\/a><\/li>\n\t\t<li id=\"menu-item-27833\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/livro-infantil-solos-floripa-2023\/\" class = \"hfe-sub-menu-item\">Solos Floripa 2023<\/a><\/li>\n\t\t<li id=\"menu-item-27834\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/maria-farinha-e-a-mare\/\" class = \"hfe-sub-menu-item\">Maria Farinha e a Mar\u00e9<\/a><\/li>\n\t\t<li id=\"menu-item-27835\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/livro-infantil-solos\/\" class = \"hfe-sub-menu-item\">Solos<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-150\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/contato\/\" class = \"hfe-menu-item\">CONTATO<\/a><\/li>\n<\/ul> \n\t\t\t\t<\/nav>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-14ab3448 elementor-sm-83\" data-id=\"14ab3448\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-724d9cb elementor-widget elementor-widget-wp-widget-search\" data-id=\"724d9cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-search.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<form aria-label=\"Pesquisar neste site\" role=\"search\" method=\"get\" class=\"searchform\" action=\"https:\/\/ciram.epagri.sc.gov.br\/\">\t\n\t<input aria-label=\"Inserir consulta de pesquisa\" type=\"search\" id=\"ocean-search-form-1\" class=\"field\" autocomplete=\"off\" placeholder=\"Pesquisar\" name=\"s\">\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-32d38769\" data-id=\"32d38769\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8d6b51 elementor-widget elementor-widget-image\" data-id=\"b8d6b51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.agricultura.sc.gov.br\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/elementor\/thumbs\/Marca_SAR-qnrpwtg4hr7zmwgct2ch5qgwt9bnndf0k7403x979q.png\" title=\"Marca_SAR\" alt=\"Marca_SAR\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33d68e6b elementor-section-stretched elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33d68e6b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c195040\" data-id=\"7c195040\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-343af092 elementor-widget elementor-widget-heading\" data-id=\"343af092\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Notas Mar\u00edtimas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bbdc81e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bbdc81e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-729e1e4\" data-id=\"729e1e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65bd30db elementor-widget elementor-widget-heading\" data-id=\"65bd30db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Confira as Notas Mar\u00edtimas da Epagri\/Ciram:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d20e16c elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3d20e16c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f96c058\" data-id=\"3f96c058\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0468d85 elementor-grid-1 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-elementor-blog-posts\" data-id=\"0468d85\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;1&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"elementor-blog-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wpcap-grid\">\n\t\t\t\t\t\t<div class=\"wpcap-grid-container elementor-grid wpcap-grid-desktop-1 wpcap-grid-tablet-2 wpcap-grid-mobile-1\">\n\n\t\t\t\t\n        <article id=\"post-1801\" class=\"wpcap-post post-1801 post type-post status-publish format-standard has-post-thumbnail hentry category-notas-maritimas category-publicacoes entry has-media\">\n         \n            <div class=\"post-grid-inner\">\n            \t\n                \t\t<h3 class=\"title\">\n\t\t\t<a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/2026\/04\/30\/inicio-da-pesca-da-tainha-de-2026-em-sc\/\">In\u00edcio da pesca da tainha de 2026, em SC<\/a>\n\t\t<\/h3>\n\t\t                \n                \t\t<div class=\"post-grid-meta\">\n\t\t\t\n\t\t\t\t<span class=\"post-date\"><time datetime=\"2026-04-30T09:12:35-03:00\">30 de abril de 2026<\/time><\/span>\n\n\t\t\t\t\t\t<\/div>\n\t\t            \t\n                \t\t\t<div class=\"post-grid-thumbnail\">\n\t\t\t\t<a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/2026\/04\/30\/inicio-da-pesca-da-tainha-de-2026-em-sc\/\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2026\/04\/CAPA_NOTA-METEOROLOGICA-72-300x225.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2026\/04\/CAPA_NOTA-METEOROLOGICA-72-300x225.png 300w, https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2026\/04\/CAPA_NOTA-METEOROLOGICA-72.png 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n        \n                <div class=\"post-grid-text-wrap\">\n\t                \t\t<div class=\"post-grid-excerpt\">\n\t\t\t<p>As condi\u00e7\u00f5es favor\u00e1veis \u00e0 pesca da tainha devem ocorrer nos primeiros dias de maio deste ano. Entre os dias 01 e 02\/05, a atua\u00e7\u00e3o mais persistente do vento sul favorece a sa\u00edda dos cardumes do estu\u00e1rio da Bacia do Prata. No dia 03\/05, o vento sul diminuiu e vira para leste\/nordeste. Estas condi\u00e7\u00f5es indicam que&hellip;<\/p>\n\t\t<\/div>\n\t\t\t                \t\t<a class=\"read-more-btn\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/2026\/04\/30\/inicio-da-pesca-da-tainha-de-2026-em-sc\/\">Leia Mais \u00bb<\/a>\n\t\t                <\/div>\n\n            <\/div><!-- .blog-inner -->\n           \n        <\/article>\n\n        \n        <article id=\"post-42066\" class=\"wpcap-post post-42066 post type-post status-publish format-standard has-post-thumbnail hentry category-notas-maritimas entry has-media\">\n         \n            <div class=\"post-grid-inner\">\n            \t\n                \t\t<h3 class=\"title\">\n\t\t\t<a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/2025\/05\/09\/final-de-semana-com-condicoes-favoraveis-a-pesca-da-tainha-de-2025-em-sc\/\">Final de semana com condi\u00e7\u00f5es favor\u00e1veis a pesca da tainha de 2025, em SC<\/a>\n\t\t<\/h3>\n\t\t                \n                \t\t<div class=\"post-grid-meta\">\n\t\t\t\n\t\t\t\t<span class=\"post-date\"><time datetime=\"2025-05-09T10:02:22-03:00\">9 de maio de 2025<\/time><\/span>\n\n\t\t\t\t\t\t<\/div>\n\t\t            \t\n                \t\t\t<div class=\"post-grid-thumbnail\">\n\t\t\t\t<a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/2025\/05\/09\/final-de-semana-com-condicoes-favoraveis-a-pesca-da-tainha-de-2025-em-sc\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2025\/05\/CAPA_NOTA-METEOROLOGICA-32-300x225.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2025\/05\/CAPA_NOTA-METEOROLOGICA-32-300x225.jpg 300w, https:\/\/ciram.epagri.sc.gov.br\/wp-content\/uploads\/2025\/05\/CAPA_NOTA-METEOROLOGICA-32.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n        \n                <div class=\"post-grid-text-wrap\">\n\t                \t\t<div class=\"post-grid-excerpt\">\n\t\t\t<p>A partir desta sexta-feira, dia 09, as condi\u00e7\u00f5es meteorol\u00f3gicas e oceanogr\u00e1ficas s\u00e3o favor\u00e1veis \u00e0 pesca da tainha. A atua\u00e7\u00e3o persistente do vento sul deve favorecer a sa\u00edda dos cardumes do estu\u00e1rio da Bacia do Prata e Lagoa dos Patos possibilitando nestes pr\u00f3ximos dias a captura de lan\u00e7os de tainha na costa catarinense. Com rela\u00e7\u00e3o \u00e0&hellip;<\/p>\n\t\t<\/div>\n\t\t\t                \t\t<a class=\"read-more-btn\" href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/2025\/05\/09\/final-de-semana-com-condicoes-favoraveis-a-pesca-da-tainha-de-2025-em-sc\/\">Leia Mais \u00bb<\/a>\n\t\t                <\/div>\n\n            <\/div><!-- .blog-inner -->\n           \n        <\/article>\n\n        \n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62ea4bef elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"62ea4bef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-302851a6\" data-id=\"302851a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45445d9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45445d9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d8ef88d\" data-id=\"4d8ef88d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79320c02 elementor-widget elementor-widget-shortcode\" data-id=\"79320c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"128\" class=\"elementor elementor-128\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34e9b8c3 elementor-section-stretched elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34e9b8c3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c77f0\" data-id=\"6c77f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66d5ee43 elementor-widget elementor-widget-spacer\" data-id=\"66d5ee43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e5978f8 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"2e5978f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-313a87e0\" data-id=\"313a87e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-709389b0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"709389b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a25e344 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2a25e344\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-3052767\" data-id=\"3052767\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61686130 elementor-widget elementor-widget-heading\" data-id=\"61686130\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Redes sociais<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12140e2e elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-invisible elementor-widget elementor-widget-social-icons\" data-id=\"12140e2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-push elementor-repeater-item-qng8wcp\" href=\"https:\/\/www.instagram.com\/epagriciram\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-animation-push elementor-repeater-item-b9f6e7f\" href=\"https:\/\/chat.whatsapp.com\/GrB7bwsuxumAW0YQSxSULR\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-push elementor-repeater-item-ff8496c\" href=\"https:\/\/youtube.com\/@EpagriCiramtv?si=ma3uVKzstVLpX4iJ\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-x-twitter elementor-animation-push elementor-repeater-item-x8zo8jb\" href=\"https:\/\/twitter.com\/epagriciram\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">X-twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-x-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-telegram elementor-animation-push elementor-repeater-item-db70578\" href=\"https:\/\/t.me\/EpagriCiram\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Telegram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-telegram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-push elementor-repeater-item-t62l05g\" href=\"https:\/\/www.facebook.com\/Epagriciram\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1062ea95 elementor-widget elementor-widget-heading\" data-id=\"1062ea95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">EPAGRI\/CIRAM<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50efdcbc elementor-widget elementor-widget-text-editor\" data-id=\"50efdcbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centro de Informa\u00e7\u00f5es de Recursos Ambientais e de Hidrometeorologia<br \/>Rodovia Admar Gonzaga, 1347 \u2013 Itacorubi<br \/>Florianopolis, SC \u2013 Brasil \u2013 CEP 88034-901<br \/>Fone: (48) 3665-5006<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a21e874 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a21e874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d1a457 elementor-widget elementor-widget-heading\" data-id=\"1d1a457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/contato\/\">FALE CONOSCO: contatociram@epagri.sc.gov.br<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-3c762661\" data-id=\"3c762661\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-595bce6a elementor-widget elementor-widget-heading\" data-id=\"595bce6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O CIRAM<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e1e71e elementor-widget elementor-widget-heading\" data-id=\"74e1e71e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-ciram\/areas-de-atuacao\/\">\u00c1reas de atua\u00e7\u00e3o<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2158b1bf elementor-widget elementor-widget-heading\" data-id=\"2158b1bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-ciram\/equipe\/\">Equipe<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d907c4f elementor-widget elementor-widget-heading\" data-id=\"1d907c4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/o-ciram\/quem-somos\/\">Quem somos<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-682df923 elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"682df923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-5e8b8b22\" data-id=\"5e8b8b22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c81b394 elementor-widget elementor-widget-heading\" data-id=\"4c81b394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">SOLU\u00c7\u00d5ES<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20b061cf elementor-widget elementor-widget-heading\" data-id=\"20b061cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/agricultura\/\">Agricultura<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e93ec2d elementor-widget elementor-widget-heading\" data-id=\"2e93ec2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/tempo-e-clima\/\">Tempo e clima<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37137fbd elementor-widget elementor-widget-heading\" data-id=\"37137fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/condicoes-externas\/\">Condi\u00e7\u00f5es extremas<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24a31469 elementor-widget elementor-widget-heading\" data-id=\"24a31469\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/rios\/\">Rios<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-323bb24f elementor-widget elementor-widget-heading\" data-id=\"323bb24f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/litoral\/\">Litoral<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2913a59d elementor-widget elementor-widget-heading\" data-id=\"2913a59d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/monitoramento\/\">Monitoramento<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63b73f5b elementor-widget elementor-widget-heading\" data-id=\"63b73f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/receba-nossos-boletins\/\">Receba nossos boletins<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3397b475 elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"3397b475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-57225028\" data-id=\"57225028\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77bcc37c elementor-widget elementor-widget-heading\" data-id=\"77bcc37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">PROJETOS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e2d1080 elementor-widget elementor-widget-heading\" data-id=\"7e2d1080\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/projetos\/projetos-concluidos\/\">Conclu\u00eddos<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f226db3 elementor-widget elementor-widget-heading\" data-id=\"4f226db3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/projetos\/projetos-em-andamento\/\">Em andamento<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f7868eb elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"7f7868eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-23ad5490\" data-id=\"23ad5490\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-249c5a49 elementor-widget elementor-widget-heading\" data-id=\"249c5a49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">SERVICOS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15f2347c elementor-widget elementor-widget-heading\" data-id=\"15f2347c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/solucoes\/laudos-dados\/\">Laudos<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69d28347 elementor-widget elementor-widget-heading\" data-id=\"69d28347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-casan-peri\/\" target=\"_blank\">Casan<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c05a24 elementor-widget elementor-widget-heading\" data-id=\"5c05a24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-queimados-projeto\/\" target=\"_blank\">Conc\u00f3rdia<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4fb44c elementor-widget elementor-widget-heading\" data-id=\"c4fb44c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/serv-porto\/\" target=\"_blank\">Porto SFS<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94c3f86 elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"94c3f86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-42a88ff1\" data-id=\"42a88ff1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41dfbab8 elementor-widget elementor-widget-heading\" data-id=\"41dfbab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">PUBLICA\u00c7\u00d5ES<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3298242c elementor-widget elementor-widget-heading\" data-id=\"3298242c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ciram.epagri.sc.gov.br\/index.php\/publicacoes\/publicacoes-tecnico-cientificas\/\">T\u00e9cnico-cient\u00edficas<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-258f222c elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"258f222c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f996a12 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4f996a12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1410dc96\" data-id=\"1410dc96\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab1f560 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7ab1f560\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-26aa7e8a elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"26aa7e8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-16d3d45\" data-id=\"16d3d45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52bdef6e elementor-widget elementor-widget-heading\" data-id=\"52bdef6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.epagri.sc.gov.br\/index.php\/politica-de-privacidade\/\" target=\"_blank\">Pol\u00edtica de Privacidade<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e04b279\" data-id=\"e04b279\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4170533f elementor-widget elementor-widget-heading\" data-id=\"4170533f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/ciram.epagri.sc.gov.br\/intra_meteorologia\/\" target=\"_blank\">Intranet Ciram<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-21ceb12c\" data-id=\"21ceb12c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b9ac122 elementor-widget elementor-widget-heading\" data-id=\"7b9ac122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/webmail.epagri.sc.gov.br\/\" target=\"_blank\">Webmail<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-603ea2f8\" data-id=\"603ea2f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51809e8c elementor-widget elementor-widget-heading\" data-id=\"51809e8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/intranet.epagri.sc.gov.br\/\" target=\"_blank\">EpagriNet<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-93cd382 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93cd382\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5878326c\" data-id=\"5878326c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69be9fe9 elementor-widget elementor-widget-copyright\" data-id=\"69be9fe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;align&quot;:&quot;center&quot;}\" data-widget_type=\"copyright.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hfe-copyright-wrapper\">\n\t\t\t\t\t\t\t<span>\u00a9 2026 Epagri\/Ciram<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Notas Mar\u00edtimas Confira as Notas Mar\u00edtimas da Epagri\/Ciram: Condi\u00e7\u00f5es Favor\u00e1veis a Pesca da Tainha 13 de maio de 2020 A previs\u00e3o de 04\/05 se confirmou, com v\u00e1rios pequemos lan\u00e7os de tainhas ao longo do litoral e outros mais expressivos registrados no farol de Santa Marta e S\u00e3o Francisco do Sul, caracterizando um bom in\u00edcio de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-281","page","type-page","status-publish","hentry","entry","has-media"],"_links":{"self":[{"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/pages\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":12,"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/pages\/281\/revisions"}],"predecessor-version":[{"id":1805,"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/pages\/281\/revisions\/1805"}],"up":[{"embeddable":true,"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/pages\/13"}],"wp:attachment":[{"href":"https:\/\/ciram.epagri.sc.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}